{"id":133558,"date":"2026-07-13T18:04:29","date_gmt":"2026-07-13T16:04:29","guid":{"rendered":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/"},"modified":"2026-07-13T18:04:29","modified_gmt":"2026-07-13T16:04:29","slug":"video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana","status":"publish","type":"post","link":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/","title":{"rendered":"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1!"},"content":{"rendered":"<p>\u00a1Aijue! El ex Gobernador de Alto Paran\u00e1 Roberto Gonz\u00e1lez Vaesken pure\u00f3 por el ingueroviable autazo que se compr\u00f3.<\/p>\n<p>El parlanch\u00edn este\u00f1o retir\u00f3 un autazo de la marca Ferrari y dijo que fue pedido de su beb\u00e9\u2019i reci\u00e9n nacido.<\/p>\n<p>\u201cVos sabes que Robertito me rompe las bolas que se quiere pasar en ese auto a las dos o las tres de la ma\u00f1ana. Y bueno, voy a tener que hacerle caso y terminar pase\u00e1ndonos\u201d, dijo el exGobernador al subir al autazo, un Ferrari, modelo Portofino.<\/p>\n<p>El precio de un Ferrari Portofino oscila entre los 160.000 y 200.000 d\u00f3lares (aproximadamente entre mil y mil doscientos millones de guaracas al cambio actual). S\u00f3lo cuatro autos de este modelo llegaron a Sudam\u00e9rica.<\/p>\n<p>\u201cEntro bien. As\u00ed somos los flacos y los milenials\u201d, dijo Roberto al subirse dentro del autazo y arrancar.<img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-348326\" src=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024112\/exoticos.en_.sudamerica_1627675118_2629451935738814568_4931206515.jpg\" alt=\"\" width=\"1080\" height=\"808\" srcset=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024112\/exoticos.en_.sudamerica_1627675118_2629451935738814568_4931206515.jpg 1080w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024112\/exoticos.en_.sudamerica_1627675118_2629451935738814568_4931206515-300x224.jpg 300w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024112\/exoticos.en_.sudamerica_1627675118_2629451935738814568_4931206515-1024x766.jpg 1024w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024112\/exoticos.en_.sudamerica_1627675118_2629451935738814568_4931206515-768x575.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/> <img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-348327\" src=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024114\/exoticos.en_.sudamerica_1627675118_2629451935428423486_4931206515.jpg\" alt=\"\" width=\"1080\" height=\"807\" srcset=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024114\/exoticos.en_.sudamerica_1627675118_2629451935428423486_4931206515.jpg 1080w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024114\/exoticos.en_.sudamerica_1627675118_2629451935428423486_4931206515-300x224.jpg 300w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024114\/exoticos.en_.sudamerica_1627675118_2629451935428423486_4931206515-1024x765.jpg 1024w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024114\/exoticos.en_.sudamerica_1627675118_2629451935428423486_4931206515-768x574.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/> <img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-348328\" src=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024117\/exoticos.en_.sudamerica_1627675118_2629451935470432276_4931206515.jpg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024117\/exoticos.en_.sudamerica_1627675118_2629451935470432276_4931206515.jpg 1080w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024117\/exoticos.en_.sudamerica_1627675118_2629451935470432276_4931206515-300x225.jpg 300w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024117\/exoticos.en_.sudamerica_1627675118_2629451935470432276_4931206515-1024x768.jpg 1024w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024117\/exoticos.en_.sudamerica_1627675118_2629451935470432276_4931206515-768x576.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/> <img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-348329\" src=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024119\/exoticos.en_.sudamerica_1627675118_2629451935478789715_4931206515.jpg\" alt=\"\" width=\"1080\" height=\"807\" srcset=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024119\/exoticos.en_.sudamerica_1627675118_2629451935478789715_4931206515.jpg 1080w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024119\/exoticos.en_.sudamerica_1627675118_2629451935478789715_4931206515-300x224.jpg 300w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024119\/exoticos.en_.sudamerica_1627675118_2629451935478789715_4931206515-1024x765.jpg 1024w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024119\/exoticos.en_.sudamerica_1627675118_2629451935478789715_4931206515-768x574.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/> <img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-348330\" src=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024121\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515.jpg\" alt=\"\" width=\"1023\" height=\"766\" srcset=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024121\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515.jpg 1023w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024121\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-300x225.jpg 300w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13024121\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-768x575.jpg 768w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/p>\n<p>\u00a0<\/p>\n<div class=\"wp-video\"><video class=\"wp-video-shortcode\" width=\"356\" height=\"638\" preload=\"none\" controls=\"controls\"><a href=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13023453\/FDownloader.Net_AQOgFqMpvvQqsuCo5W43e5Yl1lot5jINoR2KGJoIxAnaWi9bPZNsfK8jq2LSTIklPXvUen6JWsKbdUhopBuu6kQYx6aENtrrcjLneeA5vA_360p_SD.mp4\">https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13023453\/FDownloader.Net_AQOgFqMpvvQqsuCo5W43e5Yl1lot5jINoR2KGJoIxAnaWi9bPZNsfK8jq2LSTIklPXvUen6JWsKbdUhopBuu6kQYx6aENtrrcjLneeA5vA_360p_SD.mp4<\/a><\/video><\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/www.popular.com.py\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/\">(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1!<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/www.popular.com.py\/\">Popular<\/a>.<\/p>\n<p>\u00a0\u00a1Aijue! El ex Gobernador de Alto Paran\u00e1 Roberto Gonz\u00e1lez Vaesken pure\u00f3 por el ingueroviable autazo que se compr\u00f3. El parlanch\u00edn este\u00f1o retir\u00f3 un autazo de la marca Ferrari y dijo que fue pedido de su beb\u00e9\u2019i reci\u00e9n nacido. \u201cVos sabes que Robertito me rompe las bolas que se quiere pasar en ese auto a las<br \/>\nLa entrada (VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1! se public\u00f3 primero en Popular.\u00a0\u00a0<\/p>\n<p>La cocinera e influencer Giannina Alfieri en entrevista con el podcast \u201cSeas quien seas\u201d, confirm\u00f3 lo que la semana pasada te chusmeabamos.<\/p>\n<p>La machu anda otra vez novilleando luego de su pol\u00e9mica separaci\u00f3n del muralista Oz Montan\u00eda.<\/p>\n<p>La cocinera empez\u00f3 recordando lo mal que lo pas\u00f3 en su separaci\u00f3n. Giannina he\u2019i que entr\u00f3 en depresi\u00f3n voi. \u201cEmpec\u00e9 a encerrarme mucho y no quer\u00eda contarle a nadie hasta que un d\u00eda le dije a una amiga: \u2018mira yo estoy preocupada, me preocupa esta situaci\u00f3n, yo siento que no estoy bien\u2019\u201d, record\u00f3 la influencer quien tuvo que ir a muchas sesiones de terapia para superar su ruptura.<\/p>\n<p>\u201cIgual yo siempre voy a ser vyra en el amor, yo s\u00e9 eso y no voy a dejar de ser tampoco. Tampoco me quiero convertir en una piedra que te digo no, yo no creo m\u00e1s en el amor. Lo que yo aprend\u00ed es que yo s\u00e9 querer y s\u00e9 hacer una casa, s\u00e9 hacer un hogar\u201d, he\u2019i Giannina.<\/p>\n<p>La cocinera dijo que se enter\u00f3 por una amiga que estaba siendo corneada, pero que antes ya ten\u00eda sus sospechas.<\/p>\n<p>\u201cMe qued\u00f3 yo sola. Con todos los gastos que asumimos para dos personas. Pero dije que pod\u00eda sola y lo estoy haciendo sola\u201d, he\u2019i Gia.<\/p>\n<p>La cocinera luego al ser consultada si segu\u00eda sola confes\u00f3 que ahora est\u00e1 bien y no quiso revelar si est\u00e1 enamorada. Eso s\u00ed, la machu dio a entender que no es paraguayo y que tampoco es famoso.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-348313\" src=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13021736\/WhatsApp-Image-2026-07-13-at-02.16.11.jpeg\" alt=\"\" width=\"610\" height=\"1045\" srcset=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13021736\/WhatsApp-Image-2026-07-13-at-02.16.11.jpeg 610w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13021736\/WhatsApp-Image-2026-07-13-at-02.16.11-175x300.jpeg 175w, https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13021736\/WhatsApp-Image-2026-07-13-at-02.16.11-598x1024.jpeg 598w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/><\/p>\n\n<p><a href=\"https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13021032\/sebarodriguezpy.mp4\">https:\/\/popular2.nyc3.cdn.digitaloceanspaces.com\/wp-content\/uploads\/2026\/07\/13021032\/sebarodriguezpy.mp4<\/a>\u00a0Far\u00e1ndula<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Aijue! El ex Gobernador de Alto Paran\u00e1 Roberto Gonz\u00e1lez Vaesken pure\u00f3 por el ingueroviable autazo que se compr\u00f3. El parlanch\u00edn este\u00f1o retir\u00f3 un autazo de la marca Ferrari y dijo que fue pedido de su beb\u00e9\u2019i reci\u00e9n nacido. \u201cVos sabes que Robertito me rompe las bolas que se quiere pasar en ese auto a las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":133531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-133558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1! - asuncionactual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1! - asuncionactual\" \/>\n<meta property=\"og:description\" content=\"\u00a1Aijue! El ex Gobernador de Alto Paran\u00e1 Roberto Gonz\u00e1lez Vaesken pure\u00f3 por el ingueroviable autazo que se compr\u00f3. El parlanch\u00edn este\u00f1o retir\u00f3 un autazo de la marca Ferrari y dijo que fue pedido de su beb\u00e9\u2019i reci\u00e9n nacido. \u201cVos sabes que Robertito me rompe las bolas que se quiere pasar en ese auto a las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/\" \/>\n<meta property=\"og:site_name\" content=\"asuncionactual\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-13T16:04:29+00:00\" \/>\n<meta name=\"author\" content=\"info@asuncionactual.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"info@asuncionactual.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/\"},\"author\":{\"name\":\"info@asuncionactual.com\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#\\\/schema\\\/person\\\/15cb68076e092d035f0f3cdfdfba5497\"},\"headline\":\"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1!\",\"datePublished\":\"2026-07-13T16:04:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/\"},\"wordCount\":557,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asuncionactual.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-hR6gtY.jpg\",\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/\",\"url\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/\",\"name\":\"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1! - asuncionactual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asuncionactual.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-hR6gtY.jpg\",\"datePublished\":\"2026-07-13T16:04:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asuncionactual.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-hR6gtY.jpg\",\"contentUrl\":\"https:\\\/\\\/asuncionactual.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-hR6gtY.jpg\",\"width\":1023,\"height\":766},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/2026\\\/07\\\/13\\\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/asuncionactual.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#website\",\"url\":\"https:\\\/\\\/asuncionactual.com\\\/\",\"name\":\"asuncionactual\",\"description\":\"Asunci\u00f3nActual es un peri\u00f3dico digital que te ofrece noticias, informaci\u00f3n y entretenimiento relevantes para los residentes y visitantes de Asunci\u00f3n, Paraguay. Nuestro equipo de periodistas apasionados te trae las \u00faltimas novedades sobre pol\u00edtica, econom\u00eda, negocios, cultura, deportes y m\u00e1s\",\"publisher\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asuncionactual.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#organization\",\"name\":\"asuncionactual\",\"url\":\"https:\\\/\\\/asuncionactual.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asuncionactual.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/58-AsuncionActual.png\",\"contentUrl\":\"https:\\\/\\\/asuncionactual.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/58-AsuncionActual.png\",\"width\":1190,\"height\":229,\"caption\":\"asuncionactual\"},\"image\":{\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asuncionactual.com\\\/#\\\/schema\\\/person\\\/15cb68076e092d035f0f3cdfdfba5497\",\"name\":\"info@asuncionactual.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b1308c398abbb1e027645e0647929405fa3294bb2c890bb7386eeee1a1907ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b1308c398abbb1e027645e0647929405fa3294bb2c890bb7386eeee1a1907ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b1308c398abbb1e027645e0647929405fa3294bb2c890bb7386eeee1a1907ab?s=96&d=mm&r=g\",\"caption\":\"info@asuncionactual.com\"},\"sameAs\":[\"http:\\\/\\\/asuncionactual.com\"],\"url\":\"https:\\\/\\\/asuncionactual.com\\\/index.php\\\/author\\\/infoasuncionactual-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1! - asuncionactual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/","og_locale":"es_ES","og_type":"article","og_title":"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1! - asuncionactual","og_description":"\u00a1Aijue! El ex Gobernador de Alto Paran\u00e1 Roberto Gonz\u00e1lez Vaesken pure\u00f3 por el ingueroviable autazo que se compr\u00f3. El parlanch\u00edn este\u00f1o retir\u00f3 un autazo de la marca Ferrari y dijo que fue pedido de su beb\u00e9\u2019i reci\u00e9n nacido. \u201cVos sabes que Robertito me rompe las bolas que se quiere pasar en ese auto a las [&hellip;]","og_url":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/","og_site_name":"asuncionactual","article_published_time":"2026-07-13T16:04:29+00:00","author":"info@asuncionactual.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"info@asuncionactual.com","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/#article","isPartOf":{"@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/"},"author":{"name":"info@asuncionactual.com","@id":"https:\/\/asuncionactual.com\/#\/schema\/person\/15cb68076e092d035f0f3cdfdfba5497"},"headline":"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1!","datePublished":"2026-07-13T16:04:29+00:00","mainEntityOfPage":{"@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/"},"wordCount":557,"commentCount":0,"publisher":{"@id":"https:\/\/asuncionactual.com\/#organization"},"image":{"@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/#primaryimage"},"thumbnailUrl":"https:\/\/asuncionactual.com\/wp-content\/uploads\/2026\/07\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-hR6gtY.jpg","articleSection":["Entretenimiento"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/","url":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/","name":"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1! - asuncionactual","isPartOf":{"@id":"https:\/\/asuncionactual.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/#primaryimage"},"image":{"@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/#primaryimage"},"thumbnailUrl":"https:\/\/asuncionactual.com\/wp-content\/uploads\/2026\/07\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-hR6gtY.jpg","datePublished":"2026-07-13T16:04:29+00:00","breadcrumb":{"@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/#primaryimage","url":"https:\/\/asuncionactual.com\/wp-content\/uploads\/2026\/07\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-hR6gtY.jpg","contentUrl":"https:\/\/asuncionactual.com\/wp-content\/uploads\/2026\/07\/exoticos.en_.sudamerica_1627675118_2629451935747371753_4931206515-hR6gtY.jpg","width":1023,"height":766},{"@type":"BreadcrumbList","@id":"https:\/\/asuncionactual.com\/index.php\/2026\/07\/13\/video-ndetavyonde-mira-la-nave-que-se-compro-el-exgobernador-de-alto-parana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/asuncionactual.com\/"},{"@type":"ListItem","position":2,"name":"(VIDEO) \u00a1Ndetavyonde! \u00a1Mir\u00e1 la nave que se compr\u00f3 el exGobernador de Alto Paran\u00e1!"}]},{"@type":"WebSite","@id":"https:\/\/asuncionactual.com\/#website","url":"https:\/\/asuncionactual.com\/","name":"asuncionactual","description":"Asunci\u00f3nActual es un peri\u00f3dico digital que te ofrece noticias, informaci\u00f3n y entretenimiento relevantes para los residentes y visitantes de Asunci\u00f3n, Paraguay. Nuestro equipo de periodistas apasionados te trae las \u00faltimas novedades sobre pol\u00edtica, econom\u00eda, negocios, cultura, deportes y m\u00e1s","publisher":{"@id":"https:\/\/asuncionactual.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asuncionactual.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/asuncionactual.com\/#organization","name":"asuncionactual","url":"https:\/\/asuncionactual.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/asuncionactual.com\/#\/schema\/logo\/image\/","url":"https:\/\/asuncionactual.com\/wp-content\/uploads\/2024\/06\/58-AsuncionActual.png","contentUrl":"https:\/\/asuncionactual.com\/wp-content\/uploads\/2024\/06\/58-AsuncionActual.png","width":1190,"height":229,"caption":"asuncionactual"},"image":{"@id":"https:\/\/asuncionactual.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/asuncionactual.com\/#\/schema\/person\/15cb68076e092d035f0f3cdfdfba5497","name":"info@asuncionactual.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b1308c398abbb1e027645e0647929405fa3294bb2c890bb7386eeee1a1907ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b1308c398abbb1e027645e0647929405fa3294bb2c890bb7386eeee1a1907ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b1308c398abbb1e027645e0647929405fa3294bb2c890bb7386eeee1a1907ab?s=96&d=mm&r=g","caption":"info@asuncionactual.com"},"sameAs":["http:\/\/asuncionactual.com"],"url":"https:\/\/asuncionactual.com\/index.php\/author\/infoasuncionactual-com\/"}]}},"_links":{"self":[{"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/posts\/133558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/comments?post=133558"}],"version-history":[{"count":0,"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/posts\/133558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/media\/133531"}],"wp:attachment":[{"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/media?parent=133558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/categories?post=133558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asuncionactual.com\/index.php\/wp-json\/wp\/v2\/tags?post=133558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}